{"id":1231,"date":"2023-03-31T08:22:44","date_gmt":"2023-03-31T13:22:44","guid":{"rendered":"https:\/\/bydauto.com.co\/blog\/?p=1231"},"modified":"2023-03-31T08:22:46","modified_gmt":"2023-03-31T13:22:46","slug":"estos-son-los-principios-del-funcionamiento-de-un-motor-electrico","status":"publish","type":"post","link":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/","title":{"rendered":"Estos son los principios del funcionamiento de un motor el\u00e9ctrico"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"464\" src=\"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico.jpg\" alt=\"motor y bater\u00eda de los autos el\u00e9ctricos\" class=\"wp-image-157\" srcset=\"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico.jpg 768w, https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico-300x181.jpg 300w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">El motor el\u00e9ctrico de un veh\u00edculo es un componente que convierte la energ\u00eda el\u00e9ctrica almacenada en la bater\u00eda en energ\u00eda mec\u00e1nica que impulsa el movimiento de las ruedas y permite el desplazamiento del carro. En este art\u00edculo te mostramos todo lo que debes tener en cuenta para entender su funcionamiento.<\/h2>\n\n\n\n<p><strong>Para entender c\u00f3mo funciona un motor el\u00e9ctrico primero se debe tener una idea de la ley de Ampere y la ley de Faraday<\/strong>. Ambas hablan de que un flujo de corriente induce un campo magn\u00e9tico en el cual, como podemos observar con dos imanes cuando tratamos de unirlos, pueden ocurrir dos cosas: que las polaridades sean diferentes y los campos se atraigan o que las polaridades sean iguales y los campos se repelen. Y en el mismo sentido, cuando se modifica el campo magn\u00e9tico se generan corrientes en el sistema.<\/p>\n\n\n\n<p>En resumidas cuentas, esto es lo que hace que los motores el\u00e9ctricos funcionen. Cuando se introduce una corriente de entrada a un motor, internamente est\u00e1 generando un campo magn\u00e9tico que tratar\u00e1 de mover el eje unos grados. Pero como esta corriente se convierte en constante, el campo magn\u00e9tico desaparece y el motor no se sigue moviendo.<\/p>\n\n\n\n<p>Por eso <strong>los motores el\u00e9ctricos funcionan con corrientes alternas que van variando y nunca se estabilizan, generando campos magn\u00e9ticos que tambi\u00e9n son alternos<\/strong>. Es bien sabido que los motores el\u00e9ctricos tambi\u00e9n son generadores al producir corriente cuando se mueve su eje. Este principio se puede observar en las plantas de generaci\u00f3n de energ\u00eda.<\/p>\n\n\n\n<p>Te recomendamos: <a href=\"https:\/\/bydauto.com.co\/blog\/asi-funciona-el-sistema-de-carga-de-los-vehiculos-electricos\/\">As\u00ed funciona el sistema de carga de los veh\u00edculos el\u00e9ctricos<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 componentes tiene un motor el\u00e9ctrico?<\/strong><\/h3>\n\n\n\n<p>Ahora, <strong>los motores internamente est\u00e1n compuestos por dos elementos principales: el rotor y el estator.<\/strong> El primero es la parte m\u00f3vil del sistema, que generalmente se encuentra en el centro del sistema y tienen un eje de salida por el cual transmite su movimiento. <\/p>\n\n\n\n<p>Por otro lado, el rotor es el encargado de generar los campos magn\u00e9ticos y sostener todo el sistema para que los dem\u00e1s elementos funcionen.<\/p>\n\n\n\n<p>El rotor y el estator generan cierta cantidad de polos magn\u00e9ticos que tratan de alinearse, pero al ser corrientes alternas, los polos cambian haciendo que el rotor quede desalineado y gire para coincidir con sus campos contrarios, generando movimiento constante dentro del motor.<\/p>\n\n\n\n<p>Estos son los componentes b\u00e1sicos de un motor el\u00e9ctrico, pero en un carro el\u00e9ctrico se pueden encontrar otros componentes:<\/p>\n\n\n\n<p>El alternador: usado para transformar la corriente directa generada por las bater\u00edas por corriente el\u00e9ctrica.<\/p>\n\n\n\n<p>El controlador de energ\u00eda: hace de regulador de corriente y con \u00e9l se puede controlar la velocidad de giro del motor.<\/p>\n\n\n\n<p>El reductor de velocidad: un engranaje que transmite la energ\u00eda rotacional pero con menos velocidad de giro.<\/p>\n\n\n\n<p>El transformador: aumenta el voltaje de salida de las bater\u00edas para que entre al motor.<\/p>\n\n\n\n<p>Te puede interesar: <a href=\"https:\/\/youtu.be\/ocP2izcTCYk\">Coche el\u00e9ctrico, \u00bfc\u00f3mo funciona?<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 tipos de motores el\u00e9ctricos existen?<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"464\" src=\"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2021\/07\/motor-electrico-byd.jpg\" alt=\"Mantenimiento de los carros el\u00e9ctricos BYD\" class=\"wp-image-577\" srcset=\"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2021\/07\/motor-electrico-byd.jpg 768w, https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2021\/07\/motor-electrico-byd-300x181.jpg 300w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>Se puede decir que dentro de los motores de corriente alterna hay:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Motores s\u00edncronos: se les llama as\u00ed porque la frecuencia de rotaci\u00f3n es igual a la de entrada de la corriente.<\/li><li>Motores de imanes permanentes: tiene los polos definidos por imanes que est\u00e1n en el rotor del motor.<\/li><li>Motores sin escobillas: estos son de los m\u00e1s usados en carros h\u00edbridos al ser silenciosos, robustos y de poco mantenimiento.<\/li><li>Motores as\u00edncronos: la velocidad de giro de estos motores no est\u00e1 definida por la corriente de entrada, siendo poco ruidosos y muy confiables.<\/li><\/ul>\n\n\n\n<p>Este es el funcionamiento del motor el\u00e9ctrico a grandes rasgos. Sin embargo, cabe se\u00f1alar que es una rama muy grande y cubrirla en pocas palabras es insuficiente, pero puede servir de introducci\u00f3n a un mundo muy bello de corrientes el\u00e9ctricas y campos magn\u00e9ticos.<\/p>\n\n\n\n<p>Contin\u00faa leyendo: <a href=\"https:\/\/bydauto.com.co\/blog\/como-funciona-el-sistema-de-regeneracion-de-energia-de-los-carros-electricos\/\">\u00bfC\u00f3mo funciona el Sistema de Regeneraci\u00f3n de Energ\u00eda de los carros el\u00e9ctricos?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El motor el\u00e9ctrico de un veh\u00edculo es un componente que convierte la energ\u00eda el\u00e9ctrica almacenada en la bater\u00eda en energ\u00eda mec\u00e1nica que impulsa el movimiento de las ruedas y permite el desplazamiento del carro. En este art\u00edculo te mostramos todo lo que debes tener en cuenta para entender su funcionamiento. Para entender c\u00f3mo funciona un &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/\" class=\"more-link\">Seguir leyendo<span class=\"screen-reader-text\"> &#8220;Estos son los principios del funcionamiento de un motor el\u00e9ctrico&#8221;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":157,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,9],"tags":[],"class_list":["post-1231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blade-battery","category-carros-electricos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lo que debes saber para entender c\u00f3mo funciona un motor el\u00e9ctrico<\/title>\n<meta name=\"description\" content=\"El motor el\u00e9ctrico convierte la energ\u00eda el\u00e9ctrica almacenada en la bater\u00eda en energ\u00eda mec\u00e1nica que impulsa el movimiento de las ruedas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo que debes saber para entender c\u00f3mo funciona un motor el\u00e9ctrico\" \/>\n<meta property=\"og:description\" content=\"El motor el\u00e9ctrico convierte la energ\u00eda el\u00e9ctrica almacenada en la bater\u00eda en energ\u00eda mec\u00e1nica que impulsa el movimiento de las ruedas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/\" \/>\n<meta property=\"og:site_name\" content=\"BYD Auto Colombia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BYDAutoColombia\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-31T13:22:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-31T13:22:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"464\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Torres\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Torres\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/\"},\"author\":{\"name\":\"Daniel Torres\",\"@id\":\"https:\/\/bydauto.com.co\/blog\/#\/schema\/person\/97e38996cd8677f633cf07d20d82096f\"},\"headline\":\"Estos son los principios del funcionamiento de un motor el\u00e9ctrico\",\"datePublished\":\"2023-03-31T13:22:44+00:00\",\"dateModified\":\"2023-03-31T13:22:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/\"},\"wordCount\":695,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/bydauto.com.co\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico.jpg\",\"articleSection\":[\"blade battery\",\"Carros el\u00e9ctricos\"],\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/\",\"url\":\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/\",\"name\":\"Lo que debes saber para entender c\u00f3mo funciona un motor el\u00e9ctrico\",\"isPartOf\":{\"@id\":\"https:\/\/bydauto.com.co\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico.jpg\",\"datePublished\":\"2023-03-31T13:22:44+00:00\",\"dateModified\":\"2023-03-31T13:22:46+00:00\",\"description\":\"El motor el\u00e9ctrico convierte la energ\u00eda el\u00e9ctrica almacenada en la bater\u00eda en energ\u00eda mec\u00e1nica que impulsa el movimiento de las ruedas\",\"breadcrumb\":{\"@id\":\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#primaryimage\",\"url\":\"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico.jpg\",\"contentUrl\":\"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico.jpg\",\"width\":768,\"height\":464,\"caption\":\"motor y bater\u00eda de los autos el\u00e9ctricos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bydauto.com.co\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estos son los principios del funcionamiento de un motor el\u00e9ctrico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bydauto.com.co\/blog\/#website\",\"url\":\"https:\/\/bydauto.com.co\/blog\/\",\"name\":\"BYD Auto Colombia\",\"description\":\"Te damos la bienvenida al blog oficial de BYD Auto Colombia.\",\"publisher\":{\"@id\":\"https:\/\/bydauto.com.co\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bydauto.com.co\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bydauto.com.co\/blog\/#organization\",\"name\":\"BYD Auto Colombia\",\"url\":\"https:\/\/bydauto.com.co\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/bydauto.com.co\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2025\/10\/cropped-logo_oscuro_7862c2d25a.png\",\"contentUrl\":\"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2025\/10\/cropped-logo_oscuro_7862c2d25a.png\",\"width\":1290,\"height\":250,\"caption\":\"BYD Auto Colombia\"},\"image\":{\"@id\":\"https:\/\/bydauto.com.co\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/BYDAutoColombia\",\"https:\/\/www.instagram.com\/bydautocolombia\/\",\"https:\/\/www.youtube.com\/channel\/UC5T2CarA3VHbF6buuvcWPXA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/bydauto.com.co\/blog\/#\/schema\/person\/97e38996cd8677f633cf07d20d82096f\",\"name\":\"Daniel Torres\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/bydauto.com.co\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/460795ba393c7da1a1279ef49917f11f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/460795ba393c7da1a1279ef49917f11f?s=96&d=mm&r=g\",\"caption\":\"Daniel Torres\"},\"url\":\"https:\/\/bydauto.com.co\/blog\/author\/egt\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo que debes saber para entender c\u00f3mo funciona un motor el\u00e9ctrico","description":"El motor el\u00e9ctrico convierte la energ\u00eda el\u00e9ctrica almacenada en la bater\u00eda en energ\u00eda mec\u00e1nica que impulsa el movimiento de las ruedas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/","og_locale":"es_ES","og_type":"article","og_title":"Lo que debes saber para entender c\u00f3mo funciona un motor el\u00e9ctrico","og_description":"El motor el\u00e9ctrico convierte la energ\u00eda el\u00e9ctrica almacenada en la bater\u00eda en energ\u00eda mec\u00e1nica que impulsa el movimiento de las ruedas","og_url":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/","og_site_name":"BYD Auto Colombia","article_publisher":"https:\/\/www.facebook.com\/BYDAutoColombia","article_published_time":"2023-03-31T13:22:44+00:00","article_modified_time":"2023-03-31T13:22:46+00:00","og_image":[{"width":768,"height":464,"url":"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico.jpg","type":"image\/jpeg"}],"author":"Daniel Torres","twitter_misc":{"Escrito por":"Daniel Torres","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#article","isPartOf":{"@id":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/"},"author":{"name":"Daniel Torres","@id":"https:\/\/bydauto.com.co\/blog\/#\/schema\/person\/97e38996cd8677f633cf07d20d82096f"},"headline":"Estos son los principios del funcionamiento de un motor el\u00e9ctrico","datePublished":"2023-03-31T13:22:44+00:00","dateModified":"2023-03-31T13:22:46+00:00","mainEntityOfPage":{"@id":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/"},"wordCount":695,"commentCount":0,"publisher":{"@id":"https:\/\/bydauto.com.co\/blog\/#organization"},"image":{"@id":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#primaryimage"},"thumbnailUrl":"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico.jpg","articleSection":["blade battery","Carros el\u00e9ctricos"],"inLanguage":"es-CO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/","url":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/","name":"Lo que debes saber para entender c\u00f3mo funciona un motor el\u00e9ctrico","isPartOf":{"@id":"https:\/\/bydauto.com.co\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#primaryimage"},"image":{"@id":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#primaryimage"},"thumbnailUrl":"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico.jpg","datePublished":"2023-03-31T13:22:44+00:00","dateModified":"2023-03-31T13:22:46+00:00","description":"El motor el\u00e9ctrico convierte la energ\u00eda el\u00e9ctrica almacenada en la bater\u00eda en energ\u00eda mec\u00e1nica que impulsa el movimiento de las ruedas","breadcrumb":{"@id":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#primaryimage","url":"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico.jpg","contentUrl":"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2020\/10\/motor-electrico.jpg","width":768,"height":464,"caption":"motor y bater\u00eda de los autos el\u00e9ctricos"},{"@type":"BreadcrumbList","@id":"https:\/\/bydauto.com.co\/blog\/estos-son-los-principios-del-funcionamiento-de-un-motor-electrico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bydauto.com.co\/blog\/"},{"@type":"ListItem","position":2,"name":"Estos son los principios del funcionamiento de un motor el\u00e9ctrico"}]},{"@type":"WebSite","@id":"https:\/\/bydauto.com.co\/blog\/#website","url":"https:\/\/bydauto.com.co\/blog\/","name":"BYD Auto Colombia","description":"Te damos la bienvenida al blog oficial de BYD Auto Colombia.","publisher":{"@id":"https:\/\/bydauto.com.co\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bydauto.com.co\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/bydauto.com.co\/blog\/#organization","name":"BYD Auto Colombia","url":"https:\/\/bydauto.com.co\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/bydauto.com.co\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2025\/10\/cropped-logo_oscuro_7862c2d25a.png","contentUrl":"https:\/\/bydauto.com.co\/blog\/wp-content\/uploads\/2025\/10\/cropped-logo_oscuro_7862c2d25a.png","width":1290,"height":250,"caption":"BYD Auto Colombia"},"image":{"@id":"https:\/\/bydauto.com.co\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BYDAutoColombia","https:\/\/www.instagram.com\/bydautocolombia\/","https:\/\/www.youtube.com\/channel\/UC5T2CarA3VHbF6buuvcWPXA"]},{"@type":"Person","@id":"https:\/\/bydauto.com.co\/blog\/#\/schema\/person\/97e38996cd8677f633cf07d20d82096f","name":"Daniel Torres","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/bydauto.com.co\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/460795ba393c7da1a1279ef49917f11f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/460795ba393c7da1a1279ef49917f11f?s=96&d=mm&r=g","caption":"Daniel Torres"},"url":"https:\/\/bydauto.com.co\/blog\/author\/egt\/"}]}},"_links":{"self":[{"href":"https:\/\/bydauto.com.co\/blog\/wp-json\/wp\/v2\/posts\/1231"}],"collection":[{"href":"https:\/\/bydauto.com.co\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bydauto.com.co\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bydauto.com.co\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bydauto.com.co\/blog\/wp-json\/wp\/v2\/comments?post=1231"}],"version-history":[{"count":1,"href":"https:\/\/bydauto.com.co\/blog\/wp-json\/wp\/v2\/posts\/1231\/revisions"}],"predecessor-version":[{"id":1232,"href":"https:\/\/bydauto.com.co\/blog\/wp-json\/wp\/v2\/posts\/1231\/revisions\/1232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bydauto.com.co\/blog\/wp-json\/wp\/v2\/media\/157"}],"wp:attachment":[{"href":"https:\/\/bydauto.com.co\/blog\/wp-json\/wp\/v2\/media?parent=1231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bydauto.com.co\/blog\/wp-json\/wp\/v2\/categories?post=1231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bydauto.com.co\/blog\/wp-json\/wp\/v2\/tags?post=1231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}